{"id":225,"count":10,"description":"","link":"https:\/\/afrikagora.com\/dallas\/category\/professional-development\/career-business\/","name":"Career","slug":"career-business","taxonomy":"category","parent":321,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Career Archives - Dallas<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Career Archives - Dallas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afrikagora.com\/dallas\/category\/professional-development\/career-business\/\" \/>\n<meta property=\"og:site_name\" content=\"Dallas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/category\\\/professional-development\\\/career-business\\\/\",\"url\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/category\\\/professional-development\\\/career-business\\\/\",\"name\":\"Career Archives - Dallas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/category\\\/professional-development\\\/career-business\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/category\\\/professional-development\\\/career-business\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professional\u00a0Development\",\"item\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/category\\\/professional-development\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Career\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/#website\",\"url\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/\",\"name\":\"Dallas\",\"description\":\"African Expat Guide Dallas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Career Archives - Dallas","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Career Archives - Dallas","og_url":"https:\/\/afrikagora.com\/dallas\/category\/professional-development\/career-business\/","og_site_name":"Dallas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/afrikagora.com\/dallas\/category\/professional-development\/career-business\/","url":"https:\/\/afrikagora.com\/dallas\/category\/professional-development\/career-business\/","name":"Career Archives - Dallas","isPartOf":{"@id":"https:\/\/afrikagora.com\/dallas\/#website"},"breadcrumb":{"@id":"https:\/\/afrikagora.com\/dallas\/category\/professional-development\/career-business\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/afrikagora.com\/dallas\/category\/professional-development\/career-business\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/afrikagora.com\/dallas\/"},{"@type":"ListItem","position":2,"name":"Professional\u00a0Development","item":"https:\/\/afrikagora.com\/dallas\/category\/professional-development\/"},{"@type":"ListItem","position":3,"name":"Career"}]},{"@type":"WebSite","@id":"https:\/\/afrikagora.com\/dallas\/#website","url":"https:\/\/afrikagora.com\/dallas\/","name":"Dallas","description":"African Expat Guide Dallas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afrikagora.com\/dallas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/categories\/225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/categories\/321"}],"wp:post_type":[{"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/posts?categories=225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}