{"id":525859,"date":"2024-01-21T04:43:30","date_gmt":"2024-01-21T04:43:30","guid":{"rendered":"https:\/\/afrikagora.com\/dallas\/services-copy-3\/"},"modified":"2024-01-28T06:07:33","modified_gmt":"2024-01-28T06:07:33","slug":"night-life","status":"publish","type":"page","link":"https:\/\/afrikagora.com\/dallas\/night-life\/","title":{"rendered":"Night Life"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-modules.php","meta":{"_acf_changed":false,"footnotes":""},"pagetagline":[],"class_list":["post-525859","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Night Life - Dallas<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Night Life - Dallas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afrikagora.com\/dallas\/night-life\/\" \/>\n<meta property=\"og:site_name\" content=\"Dallas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-28T06:07:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/night-life\\\/\",\"url\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/night-life\\\/\",\"name\":\"Night Life - Dallas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/#website\"},\"datePublished\":\"2024-01-21T04:43:30+00:00\",\"dateModified\":\"2024-01-28T06:07:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/night-life\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/night-life\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/night-life\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Night Life\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/#website\",\"url\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/\",\"name\":\"Dallas\",\"description\":\"African Expat Guide Dallas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/afrikagora.com\\\/dallas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Night Life - Dallas","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Night Life - Dallas","og_url":"https:\/\/afrikagora.com\/dallas\/night-life\/","og_site_name":"Dallas","article_modified_time":"2024-01-28T06:07:33+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/afrikagora.com\/dallas\/night-life\/","url":"https:\/\/afrikagora.com\/dallas\/night-life\/","name":"Night Life - Dallas","isPartOf":{"@id":"https:\/\/afrikagora.com\/dallas\/#website"},"datePublished":"2024-01-21T04:43:30+00:00","dateModified":"2024-01-28T06:07:33+00:00","breadcrumb":{"@id":"https:\/\/afrikagora.com\/dallas\/night-life\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/afrikagora.com\/dallas\/night-life\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/afrikagora.com\/dallas\/night-life\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/afrikagora.com\/dallas\/"},{"@type":"ListItem","position":2,"name":"Night Life"}]},{"@type":"WebSite","@id":"https:\/\/afrikagora.com\/dallas\/#website","url":"https:\/\/afrikagora.com\/dallas\/","name":"Dallas","description":"African Expat Guide Dallas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afrikagora.com\/dallas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/pages\/525859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/comments?post=525859"}],"version-history":[{"count":1,"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/pages\/525859\/revisions"}],"predecessor-version":[{"id":525867,"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/pages\/525859\/revisions\/525867"}],"wp:attachment":[{"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/media?parent=525859"}],"wp:term":[{"taxonomy":"pagetagline","embeddable":true,"href":"https:\/\/afrikagora.com\/dallas\/wp-json\/wp\/v2\/pagetagline?post=525859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}